{"id":8580,"date":"2020-08-27T14:32:28","date_gmt":"2020-08-27T19:32:28","guid":{"rendered":"https:\/\/land.deltorro.com\/?p=8580"},"modified":"2020-08-27T15:57:32","modified_gmt":"2020-08-27T20:57:32","slug":"for-parkville-the-devil-is-in-the-details","status":"publish","type":"post","link":"https:\/\/plattecountylandmark.com\/es\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/","title":{"rendered":"Para Parkville, el diablo est\u00e1 en los detalles"},"content":{"rendered":"<p><span class=\"dropcap\" style=\"background-color: #ffffff; color: #000000; border-color: #ffffff;\">H<\/span>\u00bfHa notado que cuando entra al edificio de administraci\u00f3n del condado de Platte puede oler el aroma del gobierno del condado de Clay?<\/p>\n<hr \/>\n<p>Las cosas ciertamente se est\u00e1n poniendo interesantes en la demanda de Jason Maki vs. City of Parkville relacionada con presuntas violaciones de la Ley Missouri Sunshine. Hubo dos audiencias judiciales en el caso en dos viernes recientes, el 7 y el 21 de agosto. Vi cada audiencia en vivo a trav\u00e9s de esta cosa elegante que llaman Internet. Cosas intrigantes.<\/p>\n<p>Maki se est\u00e1 representando a s\u00ed mismo y, en mi opini\u00f3n, lo ha estado haciendo muy bien. En la audiencia del 7 de agosto, son\u00f3 m\u00e1s pulido sobre el tema que el abogado profesional de la ciudad. El fallo de ese d\u00eda sigui\u00f3 el camino de Maki, ya que el juez James Van Amburg orden\u00f3 a la ciudad que fuera m\u00e1s espec\u00edfica en sus respuestas a las preguntas planteadas por Maki en el proceso de descubrimiento.<\/p>\n<p>La audiencia del 21 de agosto (art\u00edculo en la edici\u00f3n de esta semana) termin\u00f3 cuando el juez tom\u00f3 un asunto relacionado con el uso de cuentas privadas de correo electr\u00f3nico por parte de la ciudad para discutir negocios de la ciudad bajo asesoramiento, y luego emiti\u00f3 una orden a principios de esta semana. La orden del juez, a primera vista, podr\u00eda parecer una victoria para la ciudad. Seg\u00fan una publicaci\u00f3n en nuestra p\u00e1gina de Facebook, al menos un concejal electo de la ciudad, Phil Wassmer, pens\u00f3 que era una victoria para la ciudad. Pero el diablo est\u00e1 en los detalles.<\/p>\n<p>Si bien Van Amburg neg\u00f3 las solicitudes de Maki de comunicaciones que los funcionarios de la ciudad ten\u00edan sobre o haciendo referencia a Maki y neg\u00f3 la solicitud de Maki de comunicaciones sobre solicitudes de registros abiertos presentadas por personas que no sean Maki, otra parte del fallo deja abierta la puerta para que Maki obtenga comunicaciones de los funcionarios de la ciudad. cuentas de correo privadas. Dado que el alcalde Nan Johnston ha declarado p\u00fablicamente en m\u00faltiples ocasiones que los funcionarios de la ciudad a menudo usan cuentas de correo electr\u00f3nico privadas para hablar sobre los asuntos de la ciudad y que &quot;no va en contra de la ley&quot;, esta es una gran victoria para Maki. El fallo del juez requerir\u00e1 que las nuevas solicitudes de citaci\u00f3n de Maki para estos correos electr\u00f3nicos de cuentas privadas se limiten a documentos desde el momento en que Maki hizo su solicitud de la Ley Sunshine hasta el momento en que la ciudad contrat\u00f3 a un abogado en el asunto.<\/p>\n<p>En otras palabras, no es probable que Wassmer o cualquier otro funcionario de la ciudad de Parkville est\u00e9 celebrando si ahora leyeron los detalles de la orden del juez, en lugar de solo leer el titular.<\/p>\n<hr \/>\n<p>Tambi\u00e9n son interesantes algunos de los detalles en una petici\u00f3n enmendada presentada por Maki la semana pasada. En \u00e9l, detalla el n\u00famero de supuestas violaciones de Sunshine por parte de la ciudad como ahora 59. La presentaci\u00f3n original solo enumeraba ocho.<\/p>\n<p>\u201cSe han desarrollado nuevos hechos desde que se present\u00f3 esta demanda, incluidas las respuestas de la ciudad a otras solicitudes Sunshine del Sr. Maki, que iluminaron o constituyeron otras violaciones de la Ley Sunshine\u201d, dice la petici\u00f3n enmendada. Entre las nuevas supuestas violaciones est\u00e1 que la ciudad alter\u00f3 los registros que le dio a Maki. \u201cLos campos de copia oculta en los correos electr\u00f3nicos estaban en blanco cuando otros documentos producidos por la ciudad mostraban que los mismos correos electr\u00f3nicos eran, de hecho, copia oculta a otros destinatarios, alteraciones que resultaron en que la ciudad no pusiera a disposici\u00f3n los registros solicitados, sino que solo hiciera disponibles versiones manipuladas. mientras se ocultan los destinatarios originales de esas comunicaciones\u201d.<\/p>\n<p>Este parece ser un buen momento para se\u00f1alar que, en su vida real, Jason Maki es un especialista en TI destacado y respetado. Probablemente no sea una buena idea estar jugando en su timonera, por as\u00ed decirlo.<\/p>\n<p>Para la ciudad, una acusaci\u00f3n de manipular\/ocultar registros suena como un desarrollo que podr\u00eda ser, bueno, malo.<\/p>\n<hr \/>\n<p>Adem\u00e1s, la petici\u00f3n enmendada dice que la ciudad ha cobrado a Maki por el tiempo que el personal de la ciudad pas\u00f3 investigando y revisando los registros antes de ponerlos a su disposici\u00f3n &quot;lo que una decisi\u00f3n del Tribunal de Apelaciones de Missouri (tomada despu\u00e9s de que se present\u00f3 la demanda de Maki) aclar\u00f3 que es una violaci\u00f3n de la Ley Sunshine&quot;. .\u201d De acuerdo con la reciente decisi\u00f3n de la corte de apelaciones, la Ley Sunshine solo permite que un organismo gubernamental cobre por \u201cel tiempo del personal necesario para hacer copias o transferir registros electr\u00f3nicos\u201d al responder a solicitudes de registros p\u00fablicos almacenados en instalaciones electr\u00f3nicas.<\/p>\n<hr \/>\n<p>Se ha corrido la voz de que el gobierno federal otorgar\u00e1 $50 millones a la ciudad de Kansas City para el desarrollo de tranv\u00edas. Espere que la Comisi\u00f3n del Condado de Platte intente interceptar el dinero y d\u00e1rselo a un grupo deportivo juvenil y una empresa de vacaciones en crucero.<\/p>\n<hr \/>\n<p>Soy lo suficientemente mayor para recordar cuando el FBI abri\u00f3 una investigaci\u00f3n sobre la actividad en la ciudad de Parkville.<\/p>\n<hr \/>\n<p>En los \u00faltimos meses, durante una pandemia mundial, los comisionados del condado de Platte han entregado $77,000, incluidos $20,000 en d\u00f3lares federales de CARES, en dinero libre de los contribuyentes a un grupo deportivo juvenil dirigido por la esposa del comisionado presidente del condado, $44,000 a un empresa de eliminaci\u00f3n de tatuajes propiedad del auditor del condado, $226,000 a una empresa que vende paquetes de vacaciones en crucero y $78,000 a un abogado de inmigraci\u00f3n que es hija de los due\u00f1os de esa empresa de vacaciones en crucero. A\u00fan as\u00ed, los comisionados han pasado cero d\u00f3lares de ayuda federal junto con el departamento de salud local para expandir las pruebas de COVID, ayudar en el rastreo de contactos y comprar PPE para tener a mano en caso de que las cosas vayan mal este oto\u00f1o e invierno.<\/p>\n<p>Es refrescante ver que los comisionados tienen sus prioridades en orden, \u00bfverdad?<\/p>\n<p>\u201cQuiero que trabajemos juntos para proteger a nuestros ciudadanos\u201d, dijo a The Landmark la semana pasada Mary Jo Vernon, directora del Departamento de Salud del Condado de Platte. \u201cNuestras necesidades son bastante simples\u201d.<\/p>\n<p>No hay una explicaci\u00f3n razonable para que la comisi\u00f3n del condado no transfiera una cantidad adecuada de $12.2 millones en d\u00f3lares federales de CARES al departamento de salud local. Vernon dijo que el departamento de salud hace muchas semanas, quiz\u00e1s hace meses, entreg\u00f3 a los comisionados una estimaci\u00f3n de sus necesidades financieras, incluidos los gastos que se han producido desde marzo y los gastos estimados hasta el final del a\u00f1o. Vernon fue cuidadosa con sus palabras y no critic\u00f3 directamente a los comisionados en una conversaci\u00f3n conmigo el viernes.<\/p>\n<p>\u201cSomos salud p\u00fablica. Confiamos en cient\u00edficos y expertos en salud p\u00fablica\u201d, dijo.<\/p>\n<p>Aqui estamos.<\/p>\n<p style=\"text-align: center;\"><em><strong>(Busque a Ivan Foley realizando una prueba de olor dentro del edificio de administraci\u00f3n del condado de Platte o env\u00ede un correo electr\u00f3nico a <a href=\"mailto:ivan@plattecountylandmark.com\">ivan@plattecountylandmark.com<\/a>)<\/strong><\/em><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"RkQERIn98A\"><p><a href=\"https:\/\/plattecountylandmark.com\/es\/2020\/08\/27\/parkville-accused-of-59-sunshine-violations\/\">Parkville acusado de 59 violaciones Sunshine<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u201cParkville acusado de 59 violaciones de Sunshine\u201d \u2014 The Platte County Landmark Newspaper\" src=\"https:\/\/plattecountylandmark.com\/2020\/08\/27\/parkville-accused-of-59-sunshine-violations\/embed\/#?secret=kDLBcVRO46#?secret=RkQERIn98A\" data-secret=\"RkQERIn98A\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ToNqhSmVhV\"><p><a href=\"https:\/\/plattecountylandmark.com\/es\/2020\/03\/10\/city-of-parkville-accused-of-eight-violations-of-sunshine-law\/\">Ciudad de Parkville acusada de ocho violaciones de la ley del sol<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u201cCiudad de Parkville acusada de ocho violaciones de la ley del sol\u201d \u2014 The Platte County Landmark Newspaper\" src=\"https:\/\/plattecountylandmark.com\/2020\/03\/10\/city-of-parkville-accused-of-eight-violations-of-sunshine-law\/embed\/#?secret=BEN9R1h5HJ#?secret=ToNqhSmVhV\" data-secret=\"ToNqhSmVhV\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfHa notado que cuando entra al edificio de administraci\u00f3n del condado de Platte puede oler el aroma del gobierno del condado de Clay? Las cosas ciertamente se est\u00e1n poniendo interesantes en la demanda de Jason Maki vs. City of Parkville relacionada con presuntas violaciones de la Ley Missouri Sunshine. Ha habido dos audiencias judiciales en el caso en dos [\u2026]<\/p>","protected":false},"author":4,"featured_media":8594,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override":[{"single_blog_custom":"","sidebar":"","second_sidebar":"","share_position":"","share_float_style":"","post_date_format":"","post_date_format_custom":"","post_reading_time_wpm":"","zoom_button_out_step":"1","zoom_button_in_step":"1","number_popup_post":"1"}],"image_override":[{"single_post_thumbnail_size":"","single_post_gallery_size":""}],"trending_post_position":"","trending_post_label":"","sponsored_post_label":"","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo":"","sponsored_post_desc":""},"jnews_primary_category":{"id":""},"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal"}]},"footnotes":""},"categories":[54],"tags":[15641,8905,91,37,15649,35,8906],"class_list":["post-8580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cat-between-the-lines","tag-health-department","tag-lawsuits","tag-nan-johnston","tag-parkville","tag-philip-wassmer","tag-platte-county","tag-sunshine-laws"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>For Parkville, the devil is in the details - The Platte County Landmark Newspaper<\/title>\n<meta name=\"description\" content=\"Things are certainly getting interesting in the Jason Maki vs. City of Parkville lawsuit pertaining to alleged violations of the Missouri Sunshine Law. There have been two court hearings in the case on two recent Fridays, Aug. 7 and Aug. 21. I viewed each hearing live via this fancy\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plattecountylandmark.com\/es\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"For Parkville, the devil is in the details\" \/>\n<meta property=\"og:description\" content=\"Things are certainly getting interesting in the Jason Maki vs. City of Parkville lawsuit pertaining to alleged violations of the Missouri Sunshine Law. There have been two court hearings in the case on two recent Fridays, Aug. 7 and Aug. 21. I viewed each hearing live via this fancy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plattecountylandmark.com\/es\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/\" \/>\n<meta property=\"og:site_name\" content=\"The Platte County Landmark Newspaper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PlatteCountyLandmark\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/PlatteCountyLandmark\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-27T19:32:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-27T20:57:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/08\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ivan Foley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ivanfoley\" \/>\n<meta name=\"twitter:site\" content=\"@ivanfoley\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivan Foley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/\"},\"author\":{\"name\":\"Ivan Foley\",\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/#\\\/schema\\\/person\\\/e40739f99128b6284b0aa2b5be108b3d\"},\"headline\":\"For Parkville, the devil is in the details\",\"datePublished\":\"2020-08-27T19:32:28+00:00\",\"dateModified\":\"2020-08-27T20:57:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/\"},\"wordCount\":1030,\"publisher\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/plattecountylandmark.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1\",\"keywords\":[\"Health Department\",\"Lawsuits\",\"Nan Johnston\",\"parkville\",\"Philip Wassmer\",\"platte county\",\"Sunshine Laws\"],\"articleSection\":[\"Between the Lines\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/\",\"url\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/\",\"name\":\"For Parkville, the devil is in the details - The Platte County Landmark Newspaper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/plattecountylandmark.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1\",\"datePublished\":\"2020-08-27T19:32:28+00:00\",\"dateModified\":\"2020-08-27T20:57:32+00:00\",\"description\":\"Things are certainly getting interesting in the Jason Maki vs. City of Parkville lawsuit pertaining to alleged violations of the Missouri Sunshine Law. There have been two court hearings in the case on two recent Fridays, Aug. 7 and Aug. 21. I viewed each hearing live via this fancy\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/plattecountylandmark.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/plattecountylandmark.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1\",\"width\":250,\"height\":245,\"caption\":\"Devil is in the detail\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/2020\\\/08\\\/27\\\/for-parkville-the-devil-is-in-the-details\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/plattecountylandmark.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"For Parkville, the devil is in the details\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/#website\",\"url\":\"https:\\\/\\\/plattecountylandmark.com\\\/\",\"name\":\"The Platte County Landmark Newspaper\",\"description\":\"&quot;The News You Need to Read&quot; for Platte County Missouri\",\"publisher\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/plattecountylandmark.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/#organization\",\"name\":\"The Platte County Landmark Newspaper\",\"url\":\"https:\\\/\\\/plattecountylandmark.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/plattecountylandmark.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Landmark-small-web-logo-circle.png?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/plattecountylandmark.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Landmark-small-web-logo-circle.png?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"The Platte County Landmark Newspaper\"},\"image\":{\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PlatteCountyLandmark\\\/\",\"https:\\\/\\\/x.com\\\/ivanfoley\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCptF8sYR2rZSkCQOpkkk51A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/plattecountylandmark.com\\\/#\\\/schema\\\/person\\\/e40739f99128b6284b0aa2b5be108b3d\",\"name\":\"Ivan Foley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/plattecountylandmark.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ivan-headshot.png?resize=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/plattecountylandmark.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ivan-headshot.png?resize=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/plattecountylandmark.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ivan-headshot.png?resize=96%2C96&ssl=1\",\"caption\":\"Ivan Foley\"},\"description\":\"Ivan Foley, longtime owner\\\/publisher of the Platte County Landmark, is a past winner of the national Gish Award for courage, tenacity and integrity in rural journalism, presented by the Institute for Rural Journalism and Community Issues at the University of Kentucky. He lives in Platte County not far from KCI Airport.\",\"sameAs\":[\"https:\\\/\\\/plattecountylandmark.com\",\"https:\\\/\\\/www.facebook.com\\\/PlatteCountyLandmark\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ivanfoley\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCptF8sYR2rZSkCQOpkkk51A\"],\"url\":\"https:\\\/\\\/plattecountylandmark.com\\\/es\\\/author\\\/ivanfoley\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"For Parkville, the devil is in the details - The Platte County Landmark Newspaper","description":"Things are certainly getting interesting in the Jason Maki vs. City of Parkville lawsuit pertaining to alleged violations of the Missouri Sunshine Law. There have been two court hearings in the case on two recent Fridays, Aug. 7 and Aug. 21. I viewed each hearing live via this fancy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plattecountylandmark.com\/es\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/","og_locale":"es_MX","og_type":"article","og_title":"For Parkville, the devil is in the details","og_description":"Things are certainly getting interesting in the Jason Maki vs. City of Parkville lawsuit pertaining to alleged violations of the Missouri Sunshine Law. There have been two court hearings in the case on two recent Fridays, Aug. 7 and Aug. 21. I viewed each hearing live via this fancy","og_url":"https:\/\/plattecountylandmark.com\/es\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/","og_site_name":"The Platte County Landmark Newspaper","article_publisher":"https:\/\/www.facebook.com\/PlatteCountyLandmark\/","article_author":"https:\/\/www.facebook.com\/PlatteCountyLandmark\/","article_published_time":"2020-08-27T19:32:28+00:00","article_modified_time":"2020-08-27T20:57:32+00:00","og_image":[{"width":250,"height":245,"url":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/08\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1","type":"image\/jpeg"}],"author":"Ivan Foley","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ivanfoley","twitter_site":"@ivanfoley","twitter_misc":{"Escrito por":"Ivan Foley","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/#article","isPartOf":{"@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/"},"author":{"name":"Ivan Foley","@id":"https:\/\/plattecountylandmark.com\/#\/schema\/person\/e40739f99128b6284b0aa2b5be108b3d"},"headline":"For Parkville, the devil is in the details","datePublished":"2020-08-27T19:32:28+00:00","dateModified":"2020-08-27T20:57:32+00:00","mainEntityOfPage":{"@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/"},"wordCount":1030,"publisher":{"@id":"https:\/\/plattecountylandmark.com\/#organization"},"image":{"@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/08\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1","keywords":["Health Department","Lawsuits","Nan Johnston","parkville","Philip Wassmer","platte county","Sunshine Laws"],"articleSection":["Between the Lines"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/","url":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/","name":"For Parkville, the devil is in the details - The Platte County Landmark Newspaper","isPartOf":{"@id":"https:\/\/plattecountylandmark.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/#primaryimage"},"image":{"@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/08\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1","datePublished":"2020-08-27T19:32:28+00:00","dateModified":"2020-08-27T20:57:32+00:00","description":"Things are certainly getting interesting in the Jason Maki vs. City of Parkville lawsuit pertaining to alleged violations of the Missouri Sunshine Law. There have been two court hearings in the case on two recent Fridays, Aug. 7 and Aug. 21. I viewed each hearing live via this fancy","breadcrumb":{"@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/#primaryimage","url":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/08\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1","contentUrl":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/08\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1","width":250,"height":245,"caption":"Devil is in the detail"},{"@type":"BreadcrumbList","@id":"https:\/\/plattecountylandmark.com\/2020\/08\/27\/for-parkville-the-devil-is-in-the-details\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/plattecountylandmark.com\/"},{"@type":"ListItem","position":2,"name":"For Parkville, the devil is in the details"}]},{"@type":"WebSite","@id":"https:\/\/plattecountylandmark.com\/#website","url":"https:\/\/plattecountylandmark.com\/","name":"The Platte County Landmark Newspaper","description":"&quot;The News You Need to Read&quot; for Platte County Missouri","publisher":{"@id":"https:\/\/plattecountylandmark.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plattecountylandmark.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/plattecountylandmark.com\/#organization","name":"The Platte County Landmark Newspaper","url":"https:\/\/plattecountylandmark.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/plattecountylandmark.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/04\/Landmark-small-web-logo-circle.png?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/04\/Landmark-small-web-logo-circle.png?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"The Platte County Landmark Newspaper"},"image":{"@id":"https:\/\/plattecountylandmark.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PlatteCountyLandmark\/","https:\/\/x.com\/ivanfoley","https:\/\/www.youtube.com\/channel\/UCptF8sYR2rZSkCQOpkkk51A"]},{"@type":"Person","@id":"https:\/\/plattecountylandmark.com\/#\/schema\/person\/e40739f99128b6284b0aa2b5be108b3d","name":"Ivan Foley","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/04\/ivan-headshot.png?resize=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/04\/ivan-headshot.png?resize=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/04\/ivan-headshot.png?resize=96%2C96&ssl=1","caption":"Ivan Foley"},"description":"Ivan Foley, longtime owner\/publisher of the Platte County Landmark, is a past winner of the national Gish Award for courage, tenacity and integrity in rural journalism, presented by the Institute for Rural Journalism and Community Issues at the University of Kentucky. He lives in Platte County not far from KCI Airport.","sameAs":["https:\/\/plattecountylandmark.com","https:\/\/www.facebook.com\/PlatteCountyLandmark\/","https:\/\/x.com\/https:\/\/twitter.com\/ivanfoley","https:\/\/www.youtube.com\/channel\/UCptF8sYR2rZSkCQOpkkk51A"],"url":"https:\/\/plattecountylandmark.com\/es\/author\/ivanfoley\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/plattecountylandmark.com\/wp-content\/uploads\/2020\/08\/Devil-is-in-the-detail-for-web.jpg?fit=250%2C245&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/posts\/8580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/comments?post=8580"}],"version-history":[{"count":0,"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/posts\/8580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/media\/8594"}],"wp:attachment":[{"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/media?parent=8580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/categories?post=8580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plattecountylandmark.com\/es\/wp-json\/wp\/v2\/tags?post=8580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}